{"id":92324,"date":"2021-11-12T09:11:59","date_gmt":"2021-11-12T09:11:59","guid":{"rendered":"https:\/\/leb.it\/divisioni\/senza-categoria\/inoxsea-h-24v-2\/"},"modified":"2022-11-17T16:01:37","modified_gmt":"2022-11-17T16:01:37","slug":"inoxsea-h-24v-2","status":"publish","type":"product","link":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/","title":{"rendered":"INOXSEA H 24V"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row unlock_row=&#8221;&#8221; row_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text_uppercase=&#8221;&#8221; uncode_shortcode_id=&#8221;800107&#8243;]<\/p>\n<h5 style=\"text-align: left;\">Technical drawing<\/h5>\n<p>[\/vc_custom_heading][vc_single_image media=&#8221;88792&#8243; media_width_percent=&#8221;100&#8243; uncode_shortcode_id=&#8221;208271&#8243;][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243;][vc_separator sep_color=&#8221;color-wvjs&#8221;][vc_row_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243;][vc_custom_heading text_uppercase=&#8221;&#8221; uncode_shortcode_id=&#8221;145816&#8243;]<\/p>\n<h5 style=\"text-align: left;\">Area of application:<\/h5>\n<p>[\/vc_custom_heading][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243; uncode_shortcode_id=&#8221;583469&#8243;][vc_single_image media=&#8221;88685&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;152554&#8243; media_width_pixel=&#8221;100&#8243;][vc_column_text uncode_shortcode_id=&#8221;726087&#8243;]<\/p>\n<p style=\"text-align: center;\">Nautical<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243; uncode_shortcode_id=&#8221;568251&#8243;][vc_single_image media=&#8221;88592&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;165483&#8243; media_width_pixel=&#8221;100&#8243;][vc_column_text uncode_shortcode_id=&#8221;133631&#8243;]<\/p>\n<p style=\"text-align: center;\">Van<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image media=&#8221;88429&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;202504&#8243; media_width_pixel=&#8221;100&#8243;][vc_column_text uncode_shortcode_id=&#8221;344551&#8243;]<\/p>\n<p style=\"text-align: center;\">Truck<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner row_inner_height_percent=&#8221;0&#8243; force_width_grid=&#8221;yes&#8221; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column_inner width=&#8221;1\/4&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image media=&#8221;88593&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;125178&#8243; media_width_pixel=&#8221;100&#8243;][vc_column_text uncode_shortcode_id=&#8221;747278&#8243;]<\/p>\n<p style=\"text-align: center;\">Bus<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_single_image media=&#8221;88594&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; media_width_pixel=&#8221;100&#8243; uncode_shortcode_id=&#8221;714434&#8243;][vc_column_text uncode_shortcode_id=&#8221;139651&#8243;]<\/p>\n<p style=\"text-align: center;\">Camper<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; position_horizontal=&#8221;right&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243;][vc_single_image media=&#8221;88595&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;186921&#8243; media_width_pixel=&#8221;100&#8243;][vc_column_text uncode_shortcode_id=&#8221;191272&#8243;]<\/p>\n<p style=\"text-align: center;\">Suv<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner row_inner_height_percent=&#8221;0&#8243; force_width_grid=&#8221;yes&#8221; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243;][vc_column_inner width=&#8221;1\/3&#8243;][vc_custom_heading text_uppercase=&#8221;&#8221; uncode_shortcode_id=&#8221;151259&#8243;]<\/p>\n<h5 style=\"text-align: left;\">Homologations:<\/h5>\n<p>[\/vc_custom_heading][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; position_horizontal=&#8221;right&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243;][vc_single_image media=&#8221;88249&#8243; media_width_use_pixel=&#8221;yes&#8221; alignment=&#8221;center&#8221; uncode_shortcode_id=&#8221;127262&#8243; media_width_pixel=&#8221;50&#8243;][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; position_horizontal=&#8221;right&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_separator sep_color=&#8221;color-wvjs&#8221;][vc_custom_heading text_uppercase=&#8221;&#8221; uncode_shortcode_id=&#8221;203021&#8243;]<\/p>\n<h5 style=\"text-align: left;\"><strong>Download data sheet<\/strong><\/h5>\n<p>[\/vc_custom_heading][vc_button button_color=&#8221;color-632047&#8243; size=&#8221;btn-xl&#8221; radius=&#8221;btn-circle&#8221; border_width=&#8221;0&#8243; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;205041&#8243; link=&#8221;url:https%3A%2F%2Fleb.it%2Fwp-content%2Fuploads%2F2021%2F09%2F3-Scheda-avvisatore-elettromagnetico-INOXSEA-H24V-en.pdf|target:_blank&#8221;]Download[\/vc_button][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong><span style=\"color: #ff6600; font-family: exo;\">ELECTROMAGNETIC HORN BEEPER<\/span><\/strong><\/p>\n<p>Marine trumpet for small and medium-sized boats<br \/>\nexcellent audibility at sea<br \/>\nmade of stainless steel 304<br \/>\nACUTE TONE<\/p>\n","protected":false},"featured_media":91625,"template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[238,251,257,258,267,273,232],"product_tag":[],"class_list":["post-92324","product","type-product","status-publish","has-post-thumbnail","product_cat-24v-en","product_cat-trucks-vans-and-buses","product_cat-horn","product_cat-electromagnetic","product_cat-inoxsea-en","product_cat-nautical","product_cat-horns","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera\" \/>\n<meta property=\"og:description\" content=\"ELECTROMAGNETIC HORN BEEPER  Marine trumpet for small and medium-sized boats excellent audibility at sea made of stainless steel 304 ACUTE TONE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LEB - Avvisatori Acustici e Lavorazione Lamiera\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-17T16:01:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leb.it\/wp-content\/uploads\/2021\/11\/7935-INOXSEA-H-12V.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/\",\"url\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/\",\"name\":\"INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leb.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/7935-INOXSEA-H-12V.jpg\",\"datePublished\":\"2021-11-12T09:11:59+00:00\",\"dateModified\":\"2022-11-17T16:01:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leb.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/7935-INOXSEA-H-12V.jpg\",\"contentUrl\":\"https:\\\/\\\/leb.it\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/7935-INOXSEA-H-12V.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/division\\\/horns\\\/24v-en\\\/inoxsea-h-24v-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leb.it\\\/en\\\/home-leb-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divisions\",\"item\":\"https:\\\/\\\/leb.it\\\/divisions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"INOXSEA H 24V\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/leb.it\\\/en\\\/\",\"name\":\"LEB - Avvisatori Acustici e Lavorazione Lamiera\",\"description\":\"Avvisatori Acustici e Lavorazione Lamiera\",\"publisher\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leb.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#organization\",\"name\":\"LEB S.p.A.\",\"url\":\"https:\\\/\\\/leb.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leb.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-leb-positivo.png\",\"contentUrl\":\"https:\\\/\\\/leb.it\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-leb-positivo.png\",\"width\":3000,\"height\":1356,\"caption\":\"LEB S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/leb.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/","og_locale":"en_US","og_type":"article","og_title":"INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera","og_description":"ELECTROMAGNETIC HORN BEEPER  Marine trumpet for small and medium-sized boats excellent audibility at sea made of stainless steel 304 ACUTE TONE","og_url":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/","og_site_name":"LEB - Avvisatori Acustici e Lavorazione Lamiera","article_modified_time":"2022-11-17T16:01:37+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/leb.it\/wp-content\/uploads\/2021\/11\/7935-INOXSEA-H-12V.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/","url":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/","name":"INOXSEA H 24V - LEB - Avvisatori Acustici e Lavorazione Lamiera","isPartOf":{"@id":"https:\/\/leb.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/#primaryimage"},"image":{"@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/#primaryimage"},"thumbnailUrl":"https:\/\/leb.it\/wp-content\/uploads\/2021\/11\/7935-INOXSEA-H-12V.jpg","datePublished":"2021-11-12T09:11:59+00:00","dateModified":"2022-11-17T16:01:37+00:00","breadcrumb":{"@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/#primaryimage","url":"https:\/\/leb.it\/wp-content\/uploads\/2021\/11\/7935-INOXSEA-H-12V.jpg","contentUrl":"https:\/\/leb.it\/wp-content\/uploads\/2021\/11\/7935-INOXSEA-H-12V.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/leb.it\/en\/division\/horns\/24v-en\/inoxsea-h-24v-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leb.it\/en\/home-leb-2\/"},{"@type":"ListItem","position":2,"name":"Divisions","item":"https:\/\/leb.it\/divisions\/"},{"@type":"ListItem","position":3,"name":"INOXSEA H 24V"}]},{"@type":"WebSite","@id":"https:\/\/leb.it\/en\/#website","url":"https:\/\/leb.it\/en\/","name":"LEB - Avvisatori Acustici e Lavorazione Lamiera","description":"Avvisatori Acustici e Lavorazione Lamiera","publisher":{"@id":"https:\/\/leb.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leb.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leb.it\/en\/#organization","name":"LEB S.p.A.","url":"https:\/\/leb.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leb.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/leb.it\/wp-content\/uploads\/2021\/07\/logo-leb-positivo.png","contentUrl":"https:\/\/leb.it\/wp-content\/uploads\/2021\/07\/logo-leb-positivo.png","width":3000,"height":1356,"caption":"LEB S.p.A."},"image":{"@id":"https:\/\/leb.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/product\/92324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/media\/91625"}],"wp:attachment":[{"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/media?parent=92324"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/product_brand?post=92324"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/product_cat?post=92324"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/leb.it\/en\/wp-json\/wp\/v2\/product_tag?post=92324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}